  {"id":352,"date":"2020-03-06T09:50:41","date_gmt":"2020-03-06T14:50:41","guid":{"rendered":"https:\/\/www.ramapo.edu\/rsa\/?page_id=352"},"modified":"2026-05-19T15:30:48","modified_gmt":"2026-05-19T19:30:48","slug":"meetingminutes","status":"publish","type":"page","link":"https:\/\/www.ramapo.edu\/rsa\/meetingminutes\/","title":{"rendered":"Meeting Minutes"},"content":{"rendered":"<div class=\"infoBox col-sm-12 col-lg-12 \"><div class=\"boxContent\">\n<h3 style=\"text-align: center\">RSA Meeting Minutes<\/h3>\n<div class=\"divider\"><img decoding=\"async\" src=\"\/wp-content\/themes\/rcnjrd\/images\/icons\/ramapo-arch-icom_rule.png\" alt=\"Ramapo\" \/><\/div>\n<p style=\"text-align: center\">Interested in what the RSA has been discussing? RSA meeting minutes from both Executive Board meetings and General Membership meetings will be posted here. Unless otherwise specified, the minutes are from the Executive Board meetings.<\/p>\n<p style=\"text-align: center\">Have a question about what was discussed? Reach out to us at rsa@ramapo.edu.<\/p>\n<div class=\"divider\"><img decoding=\"async\" src=\"\/wp-content\/themes\/rcnjrd\/images\/icons\/ramapo-arch-icom_rule.png\" alt=\"Ramapo\" \/><\/div>\n<div class=\"collapsableContent\" tabindex=\"0\"><div class=\"collapsableTitle\"><span class=\"fa-stack\"><i class=\"fa fa-circle fa-stack-2x\"><\/i><i class=\"fa fa-chevron-down fa-stack-1x fa-inverse\"><\/i><i class=\"fa fa-chevron-up fa-stack-1x fa-inverse\"><\/i><\/span>2025-2026 Minutes<\/div><div class=\"c_content\">\n<ul>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2026\/05\/5_19_26-Agenda.pdf\">May 19<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2026\/05\/4_21_26-Agenda.pdf\">April 21<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2026\/05\/4_13_26-Agenda.pdf\">April 13<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2026\/05\/3_24_26-Agenda-1.pdf\">March 24<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2026\/03\/3_10_26-Agenda.pdf\">March 10<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2026\/03\/2_26_26-Agenda.pdf\">February 26<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2026\/02\/2_10_26-Agenda.pdf\">February 10<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2026\/01\/1_27_26-Agenda.pdf\">January 27<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2026\/01\/1_14_25-Agenda.pdf\">January 14<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2026\/01\/1_5_26-Agenda.pdf\">January 5, 2026<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2025\/12\/12_2_25-Agenda.docx\">December 2<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2025\/12\/11_19_25-Agenda.docx\">November 19<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2025\/12\/10_14_25-Agenda.docx\">October 14<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2025\/12\/9_30_25-Agenda.docx\">September 30<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2025\/12\/9_16_25-Agenda.docx\">September 16<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2025\/12\/9_15_25-Slideshow.pptx\">September 15 (General Meeting)<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2025\/12\/9_2_2025-Agenda.docx\">September 2<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2025\/12\/8_5_2025-Agenda.docx\">August 5, 2025<\/a><\/li>\n<\/ul>\n<\/div><\/div>\n<div class=\"collapsableContent\" tabindex=\"0\"><div class=\"collapsableTitle\"><span class=\"fa-stack\"><i class=\"fa fa-circle fa-stack-2x\"><\/i><i class=\"fa fa-chevron-down fa-stack-1x fa-inverse\"><\/i><i class=\"fa fa-chevron-up fa-stack-1x fa-inverse\"><\/i><\/span>2024-2025 Minutes<\/div><div class=\"c_content\">\n<ul>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2025\/02\/2_4_25-Slideshow.pdf\">February 4, 2025 (General Meeting)<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2025\/01\/1_28_2025-Agenda.pdf\">January 28, 2025<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2025\/12\/11_19_2024-Agenda.docx\">November 19<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2024\/11\/11_12_24-Agenda.pdf\">November 12<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2024\/10\/10_29_24-Agenda.pdf\">October 29<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2024\/10\/10_15_24-Agenda.pdf\">October 15<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2025\/12\/10_8_24-Agenda.docx\">October 8<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2024\/09\/9_24_24-Agenda.pdf\">September 24<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2024\/09\/9_19_24-Slideshow.pdf\">September 19 (General Meeting)<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2024\/09\/9_17_24-Agenda.pdf\">September 17<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2024\/09\/9_10_24-Agenda.pdf\">September 10, 2024<\/a><\/li>\n<\/ul>\n<\/div><\/div>\n<div class=\"collapsableContent\" tabindex=\"0\"><div class=\"collapsableTitle\"><span class=\"fa-stack\"><i class=\"fa fa-circle fa-stack-2x\"><\/i><i class=\"fa fa-chevron-down fa-stack-1x fa-inverse\"><\/i><i class=\"fa fa-chevron-up fa-stack-1x fa-inverse\"><\/i><\/span>2023-2024 Minutes<\/div><div class=\"c_content\">\n<p>&nbsp;<\/p>\n<ul>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2024\/07\/7_1_24-Agenda.pdf\">July 1, 2024<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2024\/06\/6_11_24-Agenda.pdf\">June 11<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2024\/05\/5_20_24-Agenda.pdf\">May 20<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2024\/05\/5_7_24-Agenda.pdf\">May 7<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2024\/04\/4_23_24-Agenda.pdf\">April 23<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2024\/04\/4_16_24-Agenda.pdf\">April 16<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2024\/04\/4_2_24-Agenda.pdf\">April 2<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2024\/03\/3_26_24-Agenda.pdf\">March 26<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2024\/03\/3_19_24-General-Membership-Meeting-Minutes-1.pdf\">March 19 &#8211; General Membership Meeting<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2024\/02\/2_27_24-Agenda.pdf\">February 27<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2024\/02\/2_20_24-Agenda.pdf\">February 20<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2024\/02\/2_15_24-Agenda.pdf\">February 15 &#8211; General Membership Meeting<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2024\/02\/2_13_24-Agenda.pdf\">February 13<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2024\/02\/2_6_24-Agenda.pdf\">February 6<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2024\/02\/1_30_24-Agenda.pdf\">January 30<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2024\/01\/1_23_24-Agenda.pdf\">January 23<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2024\/01\/1_16_24-Agenda.pdf\">January 16<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2024\/01\/1_4_24-Agenda.pdf\">January 4, 2024<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2023\/12\/RSA-General-Membership-meeting-minutes-December-5.docx-1.pdf\" target=\"_blank\" rel=\"noopener\">December 5 &#8211; General Membership Meeting<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2024\/01\/11_30_23-Agenda.pdf\">November 30<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2024\/01\/11_17_23-Agenda.pdf\">November 17<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2024\/01\/10_27_23-Meeting.pdf\">October 27<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2024\/01\/9_15_23-Meeting.pdf\">September 15<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2024\/01\/9_8_23-Meeting.pdf\">September 8, 2023<\/a><\/li>\n<\/ul>\n<\/div><\/div>\n<div class=\"collapsableContent\" tabindex=\"0\"><div class=\"collapsableTitle\"><span class=\"fa-stack\"><i class=\"fa fa-circle fa-stack-2x\"><\/i><i class=\"fa fa-chevron-down fa-stack-1x fa-inverse\"><\/i><i class=\"fa fa-chevron-up fa-stack-1x fa-inverse\"><\/i><\/span>2022-2023 Minutes<\/div><div class=\"c_content\">\n<ul>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2023\/05\/May-8-2023.pdf\" target=\"_blank\" rel=\"noopener\">May 8, 2023<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2023\/05\/April-17-2023.pdf\">April 17<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2023\/05\/April-10-2023.pdf\" target=\"_blank\" rel=\"noopener\">April 10<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2023\/05\/April-3-2023.pdf\" target=\"_blank\" rel=\"noopener\">April 3<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2023\/05\/March-27-2023.pdf\" target=\"_blank\" rel=\"noopener\">March 27<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2023\/05\/March-20-2023.pdf\" target=\"_blank\" rel=\"noopener\">March 20<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2023\/03\/March-13-2023.pdf\" target=\"_blank\" rel=\"noopener\">March 13<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2023\/03\/March-6-2023.pdf\" target=\"_blank\" rel=\"noopener\">March 6<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2023\/03\/February-27-2023.pdf\" target=\"_blank\" rel=\"noopener\">February 27<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2023\/02\/February-13-2023.pdf\">February 13<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2023\/02\/January-30-2023.pdf\" target=\"_blank\" rel=\"noopener\">January 30<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2023\/02\/January-23-2023.pdf\" target=\"_blank\" rel=\"noopener\">January 23<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2023\/02\/January-9-2023.pdf\" target=\"_blank\" rel=\"noopener\">January 9, 2023<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2023\/02\/December-12-2022.pdf\" target=\"_blank\" rel=\"noopener\">December 12<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2023\/02\/November-28-2022.pdf\" target=\"_blank\" rel=\"noopener\">November 28<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2023\/02\/November-14-2022.pdf\" target=\"_blank\" rel=\"noopener\">November 14<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2023\/02\/November-7-2022.pdf\" target=\"_blank\" rel=\"noopener\">November 7<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2023\/02\/October-31-2022.pdf\" target=\"_blank\" rel=\"noopener\">October 31<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2023\/02\/October-17-2022.pdf\" target=\"_blank\" rel=\"noopener\">October 17<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2023\/02\/October-3-2022.pdf\" target=\"_blank\" rel=\"noopener\">October 3<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2023\/02\/September-26-2022.pdf\" target=\"_blank\" rel=\"noopener\">September 26<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2023\/02\/September-19-2022.pdf\" target=\"_blank\" rel=\"noopener\">September 19<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2023\/02\/September-12-2022.pdf\" target=\"_blank\" rel=\"noopener\">September 12<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2023\/02\/August-22-2022.pdf\" target=\"_blank\" rel=\"noopener\">August 22<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2023\/02\/August-1-2022.pdf\" target=\"_blank\" rel=\"noopener\">August 1, 2022<\/a><\/li>\n<\/ul>\n<\/div><\/div>\n<div class=\"collapsableContent\" tabindex=\"0\"><div class=\"collapsableTitle\"><span class=\"fa-stack\"><i class=\"fa fa-circle fa-stack-2x\"><\/i><i class=\"fa fa-chevron-down fa-stack-1x fa-inverse\"><\/i><i class=\"fa fa-chevron-up fa-stack-1x fa-inverse\"><\/i><\/span>2020-2021 Minutes<\/div><div class=\"c_content\">\n<ul>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2021\/07\/July-22-Web-Edition.pdf\">July 22, 2021<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2021\/07\/July-15-Web-Edition.pdf\">July 15<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2021\/07\/July-1-Web-Edition.pdf\">July 1<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2021\/07\/June-24-Web-Edition.pdf\">June 24<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2021\/07\/June-10-Web-Edition.pdf\">June 10<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2021\/07\/May-13-Web-Edition.pdf\">May 13<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2021\/07\/May-6-Web-Edition.pdf\">May 6<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2021\/07\/April-29-Web-Edition.pdf\">April 29<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2021\/07\/April-22-Web-Edition.pdf\">April 22<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2021\/07\/April-15-Web-Edition.pdf\">April 15<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2021\/07\/April-8-Web-Edition.pdf\">April 8<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2021\/07\/March-25-Web-Edition.pdf\">March 25<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2021\/07\/March-18-Web-Edition.pdf\">March 18<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2021\/03\/March-11-Web-Edition.pdf\">March 11<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2021\/02\/February-25-Web-Edition.pdf\">February 25<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2021\/02\/February-18-Web-Edition.pdf\">February 18<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2021\/02\/February-11-Web-Edition.pdf\">February 11<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2021\/02\/February-4-Web-Edition.pdf\">February 4<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2021\/02\/January-14-Web-Edition.pdf\">January 14<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2021\/02\/January-7-Web-Edition.pdf\">January 7, 2021<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2021\/02\/December-17-Web-Edition.pdf\">December 17<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2021\/02\/December-10-Web-Edition.pdf\">December 10<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2021\/02\/November-19-Web-Edition.pdf\">November 19<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2021\/02\/November-12-Web-Edition.pdf\">November 12<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2021\/02\/October-29-Web-Edition.pdf\">October 29<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2021\/02\/October-22-Web-Edition.pdf\">October 22<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2021\/02\/October-8-Web-Edition.pdf\">October 8<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2021\/02\/September-24-Web-Edition.pdf\">September 24<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2021\/02\/September-17-Web-Edition.pdf\">September 17<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2020\/09\/September-10-Web-Edition.pdf\">September 10<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2020\/09\/August-20-Web-Edition.pdf\">August 20, 2020<\/a><\/li>\n<\/ul>\n<\/div><\/div>\n<div class=\"collapsableContent\" tabindex=\"0\"><div class=\"collapsableTitle\"><span class=\"fa-stack\"><i class=\"fa fa-circle fa-stack-2x\"><\/i><i class=\"fa fa-chevron-down fa-stack-1x fa-inverse\"><\/i><i class=\"fa fa-chevron-up fa-stack-1x fa-inverse\"><\/i><\/span>2019-2020 Minutes<\/div><div class=\"c_content\">\n<ul>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2020\/09\/RSA-Minutes-August-6-Web-Edition.pdf\">August 6, 2020<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2020\/09\/RSA-Minutes-July-30-Web-Edition.pdf\">July 30 <\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2020\/09\/RSA-Minutes-July-9-Web-Edition.pdf\">July 9 <\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2020\/09\/RSA-Minutes-June-25-Web-Edition.pdf\">June 25\u00a0<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2020\/09\/RSA-Minutes-June-18-Web-Edition.pdf\">June 18 <\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2020\/09\/RSA-Minutes-June-2-Web-Edition.pdf\">June 2 <\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2020\/09\/RSA-Minutes-May-21-Web-Edition.pdf\">May 21 <\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2020\/09\/RSA-Minutes-May-14-Web-Edition.pdf\">May 14\u00a0<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2020\/09\/RSA-Minutes-May-7-Web-Edition.pdf\">May 7 <\/a><\/li>\n<li style=\"text-align: left\"><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2020\/05\/RSA-Minutes-April-30-Web-Edition.pdf\">April 30 <\/a><\/li>\n<li style=\"text-align: left\"><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2020\/04\/RSA-Minutes-April-24-Web-Edition.pdf\">April 24 <\/a><\/li>\n<li style=\"text-align: left\"><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2020\/04\/RSA-Minutes-April-2-2020.pdf\">April 2\u00a0<\/a><\/li>\n<li><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2020\/09\/RSA-Minutes-March-27-Web-Edition.pdf\">March 27\u00a0<\/a><\/li>\n<li style=\"text-align: left\"><a href=\"https:\/\/www.ramapo.edu\/rsa\/wp-content\/uploads\/sites\/151\/2020\/03\/RSA-Minutes-2020-03-05.pdf\">March 5, 2020<\/a><\/li>\n<\/ul>\n<\/div><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-352","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.5 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Meeting Minutes - Ramapo Staff Association || Ramapo College of New Jersey<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ramapo.edu\/rsa\/meetingminutes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Meeting Minutes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ramapo.edu\/rsa\/meetingminutes\/\" \/>\n<meta property=\"og:site_name\" content=\"Ramapo Staff Association\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RamapoCollege\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-19T19:30:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ramapocollegenj\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ramapo.edu\\\/rsa\\\/meetingminutes\\\/\",\"url\":\"https:\\\/\\\/www.ramapo.edu\\\/rsa\\\/meetingminutes\\\/\",\"name\":\"Meeting Minutes - Ramapo Staff Association || Ramapo College of New Jersey\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ramapo.edu\\\/rsa\\\/#website\"},\"datePublished\":\"2020-03-06T14:50:41+00:00\",\"dateModified\":\"2026-05-19T19:30:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ramapo.edu\\\/rsa\\\/meetingminutes\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ramapo.edu\\\/rsa\\\/meetingminutes\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ramapo.edu\\\/rsa\\\/meetingminutes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Ramapo College of New Jersey Home Page \u00bb About \u00bb College Leadership \u00bb Ramapo Staff Association\",\"item\":\"https:\\\/\\\/www.ramapo.edu\\\/rsa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Meeting Minutes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ramapo.edu\\\/rsa\\\/#website\",\"url\":\"https:\\\/\\\/www.ramapo.edu\\\/rsa\\\/\",\"name\":\"Ramapo Staff Association\",\"description\":\"To enhance connectivity among its membership while supporting institutional quality and organizational cohesion.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ramapo.edu\\\/rsa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Meeting Minutes - Ramapo Staff Association || Ramapo College of New Jersey","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ramapo.edu\/rsa\/meetingminutes\/","og_locale":"en_US","og_type":"article","og_title":"Meeting Minutes","og_url":"https:\/\/www.ramapo.edu\/rsa\/meetingminutes\/","og_site_name":"Ramapo Staff Association","article_publisher":"https:\/\/www.facebook.com\/RamapoCollege","article_modified_time":"2026-05-19T19:30:48+00:00","twitter_card":"summary_large_image","twitter_site":"@ramapocollegenj","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ramapo.edu\/rsa\/meetingminutes\/","url":"https:\/\/www.ramapo.edu\/rsa\/meetingminutes\/","name":"Meeting Minutes - Ramapo Staff Association || Ramapo College of New Jersey","isPartOf":{"@id":"https:\/\/www.ramapo.edu\/rsa\/#website"},"datePublished":"2020-03-06T14:50:41+00:00","dateModified":"2026-05-19T19:30:48+00:00","breadcrumb":{"@id":"https:\/\/www.ramapo.edu\/rsa\/meetingminutes\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ramapo.edu\/rsa\/meetingminutes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ramapo.edu\/rsa\/meetingminutes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Ramapo College of New Jersey Home Page \u00bb About \u00bb College Leadership \u00bb Ramapo Staff Association","item":"https:\/\/www.ramapo.edu\/rsa\/"},{"@type":"ListItem","position":2,"name":"Meeting Minutes"}]},{"@type":"WebSite","@id":"https:\/\/www.ramapo.edu\/rsa\/#website","url":"https:\/\/www.ramapo.edu\/rsa\/","name":"Ramapo Staff Association","description":"To enhance connectivity among its membership while supporting institutional quality and organizational cohesion.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ramapo.edu\/rsa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.ramapo.edu\/rsa\/wp-json\/wp\/v2\/pages\/352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ramapo.edu\/rsa\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ramapo.edu\/rsa\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ramapo.edu\/rsa\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ramapo.edu\/rsa\/wp-json\/wp\/v2\/comments?post=352"}],"version-history":[{"count":71,"href":"https:\/\/www.ramapo.edu\/rsa\/wp-json\/wp\/v2\/pages\/352\/revisions"}],"predecessor-version":[{"id":1140,"href":"https:\/\/www.ramapo.edu\/rsa\/wp-json\/wp\/v2\/pages\/352\/revisions\/1140"}],"wp:attachment":[{"href":"https:\/\/www.ramapo.edu\/rsa\/wp-json\/wp\/v2\/media?parent=352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}